{"id":10046,"date":"2026-05-10T19:06:43","date_gmt":"2026-05-10T23:06:43","guid":{"rendered":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/?post_type=estate-sale&#038;p=10046"},"modified":"2026-05-10T19:06:43","modified_gmt":"2026-05-10T23:06:43","slug":"blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia","status":"publish","type":"estate-sale","link":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/","title":{"rendered":"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia!"},"content":{"rendered":"","protected":false},"featured_media":10047,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"sale-category":[37,39,84,44,46,47,48,49,65,52,82,55,57,58,61],"class_list":["post-10046","estate-sale","type-estate-sale","status-publish","has-post-thumbnail","hentry","sale-category-antiques","sale-category-art-pottery","sale-category-books","sale-category-collectibles","sale-category-crafts-hobbies","sale-category-decor","sale-category-dining-kitchenware","sale-category-electronics-computers","sale-category-fashion-accessories","sale-category-furniture-lighting","sale-category-holiday","sale-category-memorabilia","sale-category-oddities","sale-category-outdoor-garden","sale-category-tools-garage-items"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia! - Blue Moon Estate Sales | Toledo - Perrysburg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Moon Estate Sales | Toledo - Perrysburg\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-content\/uploads\/sites\/68\/2026\/05\/BMES-Facebook-Header-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/\",\"name\":\"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia! - Blue Moon Estate Sales | Toledo - Perrysburg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2026\\\/05\\\/BMES-Facebook-Header-1.jpg\",\"datePublished\":\"2026-05-10T23:06:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2026\\\/05\\\/BMES-Facebook-Header-1.jpg\",\"contentUrl\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2026\\\/05\\\/BMES-Facebook-Header-1.jpg\",\"width\":1024,\"height\":379},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/estate-sale\\\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/#website\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/\",\"name\":\"Blue Moon Estate Sales | Toledo - Perrysburg\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluemoonestatesales.com\\\/toledo-perrysburg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia! - Blue Moon Estate Sales | Toledo - Perrysburg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/","og_locale":"en_US","og_type":"article","og_title":"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia!","og_url":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/","og_site_name":"Blue Moon Estate Sales | Toledo - Perrysburg","og_image":[{"width":1024,"height":379,"url":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-content\/uploads\/sites\/68\/2026\/05\/BMES-Facebook-Header-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/","url":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/","name":"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia! - Blue Moon Estate Sales | Toledo - Perrysburg","isPartOf":{"@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/#primaryimage"},"image":{"@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/#primaryimage"},"thumbnailUrl":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-content\/uploads\/sites\/68\/2026\/05\/BMES-Facebook-Header-1.jpg","datePublished":"2026-05-10T23:06:43+00:00","breadcrumb":{"@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/#primaryimage","url":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-content\/uploads\/sites\/68\/2026\/05\/BMES-Facebook-Header-1.jpg","contentUrl":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-content\/uploads\/sites\/68\/2026\/05\/BMES-Facebook-Header-1.jpg","width":1024,"height":379},{"@type":"BreadcrumbList","@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/estate-sale\/blue-moon-oregon-sale-furniture-decor-collectables-sports-memorabilia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/"},{"@type":"ListItem","position":2,"name":"Blue Moon Oregon Sale! Furniture, Decor, Collectables, Sports memorabilia!"}]},{"@type":"WebSite","@id":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/#website","url":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/","name":"Blue Moon Estate Sales | Toledo - Perrysburg","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-json\/wp\/v2\/estate-sale\/10046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-json\/wp\/v2\/estate-sale"}],"about":[{"href":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-json\/wp\/v2\/types\/estate-sale"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-json\/wp\/v2\/media\/10047"}],"wp:attachment":[{"href":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-json\/wp\/v2\/media?parent=10046"}],"wp:term":[{"taxonomy":"sale-category","embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/toledo-perrysburg\/wp-json\/wp\/v2\/sale-category?post=10046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}