{"id":1663,"date":"2024-07-31T18:46:12","date_gmt":"2024-07-31T18:46:12","guid":{"rendered":"https:\/\/bluemoonestatesales.com\/template\/?page_id=1663"},"modified":"2025-02-21T15:36:54","modified_gmt":"2025-02-21T20:36:54","slug":"how-we-help","status":"publish","type":"page","link":"https:\/\/bluemoonestatesales.com\/template\/how-we-help\/","title":{"rendered":"How We Help"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1663","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How We Help - Template Site | Blue Moon Estate Sales<\/title>\n<meta name=\"description\" content=\"See how Blue Moon Estate Sales assists those looking to buy and sell accumulated goods, as well as real estate professionals looking to partner with us.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How We Help\" \/>\n<meta property=\"og:description\" content=\"See how Blue Moon Estate Sales assists those looking to buy and sell accumulated goods, as well as real estate professionals looking to partner with us.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluemoonestatesales.com\/template\/how-we-help\/\" \/>\n<meta property=\"og:site_name\" content=\"Template Site\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T20:36:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/how-we-help\\\/\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/how-we-help\\\/\",\"name\":\"How We Help - Template Site | Blue Moon Estate Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/#website\"},\"datePublished\":\"2024-07-31T18:46:12+00:00\",\"dateModified\":\"2025-02-21T20:36:54+00:00\",\"description\":\"See how Blue Moon Estate Sales assists those looking to buy and sell accumulated goods, as well as real estate professionals looking to partner with us.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/how-we-help\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/how-we-help\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/how-we-help\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How We Help\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/#website\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/\",\"name\":\"Template Site\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluemoonestatesales.com\\\/template\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"How We Help - Template Site | Blue Moon Estate Sales","description":"See how Blue Moon Estate Sales assists those looking to buy and sell accumulated goods, as well as real estate professionals looking to partner with us.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"How We Help","og_description":"See how Blue Moon Estate Sales assists those looking to buy and sell accumulated goods, as well as real estate professionals looking to partner with us.","og_url":"https:\/\/bluemoonestatesales.com\/template\/how-we-help\/","og_site_name":"Template Site","article_modified_time":"2025-02-21T20:36:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluemoonestatesales.com\/template\/how-we-help\/","url":"https:\/\/bluemoonestatesales.com\/template\/how-we-help\/","name":"How We Help - Template Site | Blue Moon Estate Sales","isPartOf":{"@id":"https:\/\/bluemoonestatesales.com\/template\/#website"},"datePublished":"2024-07-31T18:46:12+00:00","dateModified":"2025-02-21T20:36:54+00:00","description":"See how Blue Moon Estate Sales assists those looking to buy and sell accumulated goods, as well as real estate professionals looking to partner with us.","breadcrumb":{"@id":"https:\/\/bluemoonestatesales.com\/template\/how-we-help\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluemoonestatesales.com\/template\/how-we-help\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bluemoonestatesales.com\/template\/how-we-help\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bluemoonestatesales.com\/template\/"},{"@type":"ListItem","position":2,"name":"How We Help"}]},{"@type":"WebSite","@id":"https:\/\/bluemoonestatesales.com\/template\/#website","url":"https:\/\/bluemoonestatesales.com\/template\/","name":"Template Site","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluemoonestatesales.com\/template\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bluemoonestatesales.com\/template\/wp-json\/wp\/v2\/pages\/1663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluemoonestatesales.com\/template\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bluemoonestatesales.com\/template\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/template\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/template\/wp-json\/wp\/v2\/comments?post=1663"}],"version-history":[{"count":0,"href":"https:\/\/bluemoonestatesales.com\/template\/wp-json\/wp\/v2\/pages\/1663\/revisions"}],"wp:attachment":[{"href":"https:\/\/bluemoonestatesales.com\/template\/wp-json\/wp\/v2\/media?parent=1663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}