{"id":478,"date":"2024-07-17T14:14:20","date_gmt":"2024-07-17T14:14:20","guid":{"rendered":"https:\/\/bluemoonestatesales.com\/spokane-cda\/?page_id=478"},"modified":"2024-12-19T11:28:51","modified_gmt":"2024-12-19T16:28:51","slug":"homepage","status":"publish","type":"page","link":"https:\/\/bluemoonestatesales.com\/spokane-cda\/","title":{"rendered":"Homepage"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-homepage.php","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-478","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Homepage - Blue Moon Estate Sales | Spokane\/CDA | Blue Moon Estate Sales<\/title>\n<meta name=\"description\" content=\"Blue Moon Estate Sales gives families and items a fresh start. Shop or sell your items quickly and locally. Visit the Blue Moon website to learn more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluemoonestatesales.com\/spokane-cda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homepage\" \/>\n<meta property=\"og:description\" content=\"Blue Moon Estate Sales gives families and items a fresh start. Shop or sell your items quickly and locally. Visit the Blue Moon website to learn more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluemoonestatesales.com\/spokane-cda\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Moon Estate Sales | Spokane\/CDA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T16:28:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/\",\"name\":\"Homepage - Blue Moon Estate Sales | Spokane\\\/CDA | Blue Moon Estate Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/#website\"},\"datePublished\":\"2024-07-17T14:14:20+00:00\",\"dateModified\":\"2024-12-19T16:28:51+00:00\",\"description\":\"Blue Moon Estate Sales gives families and items a fresh start. Shop or sell your items quickly and locally. Visit the Blue Moon website to learn more.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/#website\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/\",\"name\":\"Blue Moon Estate Sales | Spokane\\\/CDA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluemoonestatesales.com\\\/spokane-cda\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Homepage - Blue Moon Estate Sales | Spokane\/CDA | Blue Moon Estate Sales","description":"Blue Moon Estate Sales gives families and items a fresh start. Shop or sell your items quickly and locally. Visit the Blue Moon website to learn more.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluemoonestatesales.com\/spokane-cda\/","og_locale":"en_US","og_type":"article","og_title":"Homepage","og_description":"Blue Moon Estate Sales gives families and items a fresh start. Shop or sell your items quickly and locally. Visit the Blue Moon website to learn more.","og_url":"https:\/\/bluemoonestatesales.com\/spokane-cda\/","og_site_name":"Blue Moon Estate Sales | Spokane\/CDA","article_modified_time":"2024-12-19T16:28:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluemoonestatesales.com\/spokane-cda\/","url":"https:\/\/bluemoonestatesales.com\/spokane-cda\/","name":"Homepage - Blue Moon Estate Sales | Spokane\/CDA | Blue Moon Estate Sales","isPartOf":{"@id":"https:\/\/bluemoonestatesales.com\/spokane-cda\/#website"},"datePublished":"2024-07-17T14:14:20+00:00","dateModified":"2024-12-19T16:28:51+00:00","description":"Blue Moon Estate Sales gives families and items a fresh start. Shop or sell your items quickly and locally. Visit the Blue Moon website to learn more.","breadcrumb":{"@id":"https:\/\/bluemoonestatesales.com\/spokane-cda\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluemoonestatesales.com\/spokane-cda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bluemoonestatesales.com\/spokane-cda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bluemoonestatesales.com\/spokane-cda\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/bluemoonestatesales.com\/spokane-cda\/#website","url":"https:\/\/bluemoonestatesales.com\/spokane-cda\/","name":"Blue Moon Estate Sales | Spokane\/CDA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluemoonestatesales.com\/spokane-cda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bluemoonestatesales.com\/spokane-cda\/wp-json\/wp\/v2\/pages\/478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluemoonestatesales.com\/spokane-cda\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bluemoonestatesales.com\/spokane-cda\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/spokane-cda\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/spokane-cda\/wp-json\/wp\/v2\/comments?post=478"}],"version-history":[{"count":0,"href":"https:\/\/bluemoonestatesales.com\/spokane-cda\/wp-json\/wp\/v2\/pages\/478\/revisions"}],"wp:attachment":[{"href":"https:\/\/bluemoonestatesales.com\/spokane-cda\/wp-json\/wp\/v2\/media?parent=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}