{"id":557,"date":"2024-07-17T19:37:12","date_gmt":"2024-07-17T19:37:12","guid":{"rendered":"https:\/\/bluemoonestatesales.com\/delaware\/?page_id=557"},"modified":"2025-02-26T09:55:52","modified_gmt":"2025-02-26T14:55:52","slug":"shop-our-sales","status":"publish","type":"page","link":"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/","title":{"rendered":"Shop Our Sales"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-557","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Our Sales - Blue Moon Estate Sales | Delaware | Blue Moon Estate Sales<\/title>\n<meta name=\"description\" content=\"Discover local sales hosted by the Blue Moon Estate Sales&#039; Blue Moon Estate Sales | Delaware franchise location. Find valuable information about each sale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shop Our Sales\" \/>\n<meta property=\"og:description\" content=\"Discover local sales hosted by the Blue Moon Estate Sales&#039; Blue Moon Estate Sales | Delaware franchise location. Find valuable information about each sale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Moon Estate Sales | Delaware\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-26T14:55:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/shop-our-sales\\\/\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/shop-our-sales\\\/\",\"name\":\"Our Sales - Blue Moon Estate Sales | Delaware | Blue Moon Estate Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/#website\"},\"datePublished\":\"2024-07-17T19:37:12+00:00\",\"dateModified\":\"2025-02-26T14:55:52+00:00\",\"description\":\"Discover local sales hosted by the Blue Moon Estate Sales' Blue Moon Estate Sales | Delaware franchise location. Find valuable information about each sale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/shop-our-sales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/shop-our-sales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/shop-our-sales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop Our Sales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/#website\",\"url\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/\",\"name\":\"Blue Moon Estate Sales | Delaware\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bluemoonestatesales.com\\\/delaware\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Our Sales - Blue Moon Estate Sales | Delaware | Blue Moon Estate Sales","description":"Discover local sales hosted by the Blue Moon Estate Sales' Blue Moon Estate Sales | Delaware franchise location. Find valuable information about each sale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/","og_locale":"en_US","og_type":"article","og_title":"Shop Our Sales","og_description":"Discover local sales hosted by the Blue Moon Estate Sales' Blue Moon Estate Sales | Delaware franchise location. Find valuable information about each sale.","og_url":"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/","og_site_name":"Blue Moon Estate Sales | Delaware","article_modified_time":"2025-02-26T14:55:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/","url":"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/","name":"Our Sales - Blue Moon Estate Sales | Delaware | Blue Moon Estate Sales","isPartOf":{"@id":"https:\/\/bluemoonestatesales.com\/delaware\/#website"},"datePublished":"2024-07-17T19:37:12+00:00","dateModified":"2025-02-26T14:55:52+00:00","description":"Discover local sales hosted by the Blue Moon Estate Sales' Blue Moon Estate Sales | Delaware franchise location. Find valuable information about each sale.","breadcrumb":{"@id":"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bluemoonestatesales.com\/delaware\/shop-our-sales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bluemoonestatesales.com\/delaware\/"},{"@type":"ListItem","position":2,"name":"Shop Our Sales"}]},{"@type":"WebSite","@id":"https:\/\/bluemoonestatesales.com\/delaware\/#website","url":"https:\/\/bluemoonestatesales.com\/delaware\/","name":"Blue Moon Estate Sales | Delaware","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluemoonestatesales.com\/delaware\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bluemoonestatesales.com\/delaware\/wp-json\/wp\/v2\/pages\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluemoonestatesales.com\/delaware\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bluemoonestatesales.com\/delaware\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/delaware\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/bluemoonestatesales.com\/delaware\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":0,"href":"https:\/\/bluemoonestatesales.com\/delaware\/wp-json\/wp\/v2\/pages\/557\/revisions"}],"wp:attachment":[{"href":"https:\/\/bluemoonestatesales.com\/delaware\/wp-json\/wp\/v2\/media?parent=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}